{"id":82101,"date":"2026-08-11T17:58:26","date_gmt":"2026-08-11T17:58:26","guid":{"rendered":"https:\/\/info-teulada-moraira.com\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/"},"modified":"2026-08-11T19:31:46","modified_gmt":"2026-08-11T19:31:46","slug":"re09-ksq6vx-villa-en-venta-en-moraira","status":"publish","type":"property","link":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/","title":{"rendered":"RE09-KSQ6VX  Villa en venta en Moraira"},"content":{"rendered":"\nEsta impresionante villa de dise&#xF1;o contempor&#xE1;neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est&#xE1; construida sobre una parcela de 969 m2 con orientaci&#xF3;n este y vistas panor&#xE1;micas al mar.El dise&#xF1;o de este chalet de obra nueva surge de la necesidad de crear una casa con un dise&#xF1;o elegante, en la que sus habitantes puedan disfrutar de las vistas al mar desde todas las estancias de la casa sin perder la esencia de vivir en una casa c&#xE1;lida y acogedora. La distribuci&#xF3;n se divide en zonas de d&#xED;a, planta baja, y zonas de noche, planta superior donde se ubican los dormitorios. La casa dispone de varias zonas de invierno y verano donde poder alojarse dependiendo del sol.La piscina est&#xE1; orientada al sur y rodea la sala de estar para refrescar el ambiente. Con carpinter&#xED;a minimalista empotrada en el suelo, los espacios tienden a estar m&#xE1;s conectados con el exterior y armoniosamente integrados.\r\n<div style=\"background: #f7f7f7; padding: 15px; border-radius: 8px; text-align: center; margin-top: 20px;\">\r\n\r\n<img decoding=\"async\" style=\"width: 100%; max-width: 260px;\" src=\"\/wp-content\/uploads\/2026\/04\/energie-1.png\" \/>\r\n<p style=\"margin-top: 10px; font-weight: 600;\">Energy certificate in progress<\/p>\r\n\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta impresionante villa de dise&#xF1;o contempor&#xE1;neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est&#xE1; construida sobre una parcela de 969 m2 con orientaci&#xF3;n este y vistas panor&#xE1;micas al mar.El dise&#xF1;o de este chalet de obra nueva surge [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81017,"parent":0,"menu_order":0,"template":"","property_type":[684],"property_status":[],"property_feature":[798,829,1103],"property_label":[],"property_country":[678],"property_state":[679],"property_city":[689],"property_area":[717],"class_list":["post-82101","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_feature-vistas-vistas-al-mar","property_feature-calefaccion-suelo-radiante","property_feature-cocina-kitchen-appliances","property_country-spain","property_state-alicante","property_city-moraira","property_area-moraira"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFO Teulada Moraira\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Info Teulada Moraira -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-08-11T17:58:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-11T19:31:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/#listItem\",\"name\":\"Propiedades\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/#listItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property-type\\\/villa\\\/#listItem\",\"name\":\"Villa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property-type\\\/villa\\\/#listItem\",\"position\":3,\"name\":\"Villa\",\"item\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property-type\\\/villa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#listItem\",\"name\":\"RE09-KSQ6VX  Villa en venta en Moraira\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/#listItem\",\"name\":\"Propiedades\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#listItem\",\"position\":4,\"name\":\"RE09-KSQ6VX  Villa en venta en Moraira\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property-type\\\/villa\\\/#listItem\",\"name\":\"Villa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#organization\",\"name\":\"Info Teulada Moraira\",\"url\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/author\\\/info\\\/#author\",\"url\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/author\\\/info\\\/\",\"name\":\"INFO Teulada Moraira\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#webpage\",\"url\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/\",\"name\":\"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira\",\"description\":\"Esta impresionante villa de dise\\u00f1o contempor\\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\\u00e1 construida sobre una parcela de 969 m2 con orientaci\\u00f3n este y vistas panor\\u00e1micas al mar.El dise\\u00f1o de este chalet de obra nueva surge\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/author\\\/info\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/author\\\/info\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/info-teulada-moraira.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#mainImage\",\"width\":1680,\"height\":945,\"caption\":\"Villa for sale in Moraira\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/property\\\/re09-ksq6vx-villa-en-venta-en-moraira\\\/#mainImage\"},\"datePublished\":\"2026-08-11T17:58:26+00:00\",\"dateModified\":\"2026-08-11T19:31:46+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/\",\"name\":\"Info Teulada Moraira\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/info-teulada-moraira.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira","description":"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge","canonical_url":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/info-teulada-moraira.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/#listItem","name":"Propiedades"}},{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/#listItem","position":2,"name":"Propiedades","item":"https:\/\/info-teulada-moraira.com\/es\/property\/","nextItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/#listItem","name":"Villa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/#listItem","position":3,"name":"Villa","item":"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#listItem","name":"RE09-KSQ6VX  Villa en venta en Moraira"},"previousItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/#listItem","name":"Propiedades"}},{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#listItem","position":4,"name":"RE09-KSQ6VX  Villa en venta en Moraira","previousItem":{"@type":"ListItem","@id":"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/#listItem","name":"Villa"}}]},{"@type":"Organization","@id":"https:\/\/info-teulada-moraira.com\/es\/#organization","name":"Info Teulada Moraira","url":"https:\/\/info-teulada-moraira.com\/es\/"},{"@type":"Person","@id":"https:\/\/info-teulada-moraira.com\/es\/author\/info\/#author","url":"https:\/\/info-teulada-moraira.com\/es\/author\/info\/","name":"INFO Teulada Moraira"},{"@type":"WebPage","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#webpage","url":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/","name":"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira","description":"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/info-teulada-moraira.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#breadcrumblist"},"author":{"@id":"https:\/\/info-teulada-moraira.com\/es\/author\/info\/#author"},"creator":{"@id":"https:\/\/info-teulada-moraira.com\/es\/author\/info\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg","@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#mainImage","width":1680,"height":945,"caption":"Villa for sale in Moraira"},"primaryImageOfPage":{"@id":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/#mainImage"},"datePublished":"2026-08-11T17:58:26+00:00","dateModified":"2026-08-11T19:31:46+00:00"},{"@type":"WebSite","@id":"https:\/\/info-teulada-moraira.com\/es\/#website","url":"https:\/\/info-teulada-moraira.com\/es\/","name":"Info Teulada Moraira","inLanguage":"es-ES","publisher":{"@id":"https:\/\/info-teulada-moraira.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Info Teulada Moraira -","og:type":"article","og:title":"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira","og:description":"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge","og:url":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/","article:published_time":"2026-08-11T17:58:26+00:00","article:modified_time":"2026-08-11T19:31:46+00:00","twitter:card":"summary_large_image","twitter:title":"RE09-KSQ6VX Villa en venta en Moraira - Info Teulada Moraira","twitter:description":"Esta impresionante villa de dise\u00f1o contempor\u00e1neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est\u00e1 construida sobre una parcela de 969 m2 con orientaci\u00f3n este y vistas panor\u00e1micas al mar.El dise\u00f1o de este chalet de obra nueva surge"},"aioseo_meta_data":{"post_id":"82101","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-08-19 21:37:11","updated":"2026-08-19 21:37:11","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/info-teulada-moraira.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/info-teulada-moraira.com\/es\/property\/\" title=\"Propiedades\">Propiedades<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/\" title=\"Villa\">Villa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRE09-KSQ6VX  Villa en venta en Moraira\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/info-teulada-moraira.com\/es\/"},{"label":"Propiedades","link":"https:\/\/info-teulada-moraira.com\/es\/property\/"},{"label":"Villa","link":"https:\/\/info-teulada-moraira.com\/es\/property-type\/villa\/"},{"label":"RE09-KSQ6VX  Villa en venta en Moraira","link":"https:\/\/info-teulada-moraira.com\/es\/property\/re09-ksq6vx-villa-en-venta-en-moraira\/"}],"property_meta":{"_wp_page_template":["default"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"copied_media_ids":["a:1:{i:0;i:0;}"],"referenced_media_ids":["a:0:{}"],"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["2440000"],"fave_property_size":["424"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land":["969"],"fave_property_land_postfix":["m\u00b2"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["3"],"fave_property_map":["1"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["author_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"floor_plans":[null],"fave_multi_units":[null],"additional_features":[null],"fave_property_map_address":["Moraira Moraira"],"fave_property_location":[","],"houzez_geolocation_lat":[""],"houzez_geolocation_long":[""],"fave_property_images":["81017","81018","81019","81020","81021","81022","81023","81024","81025","81026","81027","81028"],"_thumbnail_id":["81017"],"_wpml_media_has_media":["1"],"fave_agents":["45893"],"_wpml_word_count":["186"],"houzez_total_property_views":["19"],"houzez_views_by_date":["a:13:{s:10:\"08-11-2026\";i:2;s:10:\"08-12-2026\";i:2;s:10:\"08-15-2026\";i:1;s:10:\"08-16-2026\";i:3;s:10:\"08-18-2026\";i:1;s:10:\"08-19-2026\";i:1;s:10:\"08-20-2026\";i:1;s:10:\"08-21-2026\";i:2;s:10:\"08-22-2026\";i:1;s:10:\"08-23-2026\";i:2;s:10:\"08-24-2026\";i:1;s:10:\"08-31-2026\";i:1;s:10:\"09-02-2026\";i:1;}"],"houzez_recently_viewed":["2026-09-02 08:14:23"],"_uag_css_file_name":["uag-css-82101.css"],"_uag_js_file_name":["uag-js-82101.js"],"_elementor_page_assets":["a:0:{}"]},"uagb_featured_image_src":{"full":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",1680,945,false],"thumbnail":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",150,84,false],"medium":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",300,169,false],"medium_large":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",768,432,false],"large":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",1024,576,false],"1536x1536":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f.jpg",1680,945,false],"houzez-gallery":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f-1170x785.jpg",1170,785,true],"houzez-top-v7":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f-780x780.jpg",780,780,true],"houzez-item-image-6":["https:\/\/info-teulada-moraira.com\/wp-content\/uploads\/2026\/08\/o_1fngvkvpkhbrm8c13o1r5b20t1f-584x438.jpg",584,438,true]},"uagb_author_info":{"display_name":"INFO Teulada Moraira","author_link":"https:\/\/info-teulada-moraira.com\/es\/author\/info\/"},"uagb_comment_info":0,"uagb_excerpt":"Esta impresionante villa de dise&#xF1;o contempor&#xE1;neo se encuentra en la ladera del encantador pueblo de Moraira, una zona muy tranquila con un hermoso paisaje en la provincia de Alicante. La casa est&#xE1; construida sobre una parcela de 969 m2 con orientaci&#xF3;n este y vistas panor&#xE1;micas al mar.El dise&#xF1;o de este chalet de obra nueva surge&hellip;","_links":{"self":[{"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/properties\/82101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/properties\/82101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/media\/81017"}],"wp:attachment":[{"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/media?parent=82101"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_type?post=82101"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_status?post=82101"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_feature?post=82101"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_label?post=82101"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_country?post=82101"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_state?post=82101"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_city?post=82101"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/info-teulada-moraira.com\/es\/wp-json\/wp\/v2\/property_area?post=82101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}